{"id":7759,"date":"2021-06-14T16:57:08","date_gmt":"2021-06-14T14:57:08","guid":{"rendered":"https:\/\/spmaskiner.com\/cabezales-procesadores\/cabezales-procesadores-e\/cabezales-procesadores-sp-761-e\/sp-761-e-sistemas-de-control\/"},"modified":"2025-10-17T11:18:55","modified_gmt":"2025-10-17T09:18:55","slug":"sp-761-e-sistemas-de-control","status":"publish","type":"page","link":"https:\/\/spmaskiner.com\/es\/cabezales-procesadores\/cabezales-procesadores-e\/cabezales-procesadores-sp-761-e\/sp-761-e-sistemas-de-control\/","title":{"rendered":"SP 761 E  Sistemas de control"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7759\" class=\"elementor elementor-7759 elementor-4073\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-350464f9 elementor-section-height-min-height elementor-section-items-top product-top-section elementor-section-boxed elementor-section-height-default\" data-id=\"350464f9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4f64430f\" data-id=\"4f64430f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-85aeac0 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"85aeac0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SP 761 E<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-13cf71ea\" data-id=\"13cf71ea\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-62a7671a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"62a7671a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7a34a1e8\" data-id=\"7a34a1e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed3ff97 e--pointer-background elementor-nav-menu--dropdown-mobile ecs-nav-layout-horizontal e--animation-fade elementor-nav-menu--toggle elementor-nav-menu--burger ecs-toggle-align-center elementor-widget elementor-widget-global elementor-global-3352 elementor-widget-nav-menu\" data-id=\"ed3ff97\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"product-menu\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;fas fa-caret-down&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fa\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-background e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-ed3ff97\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8080\"><a href=\"https:\/\/spmaskiner.com\/es\/cabezales-procesadores\/cabezales-procesadores-e\/cabezales-procesadores-sp-761-e\/\" class=\"elementor-item menu-link\">Informaci\u00f3n del Producto<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8081\"><a href=\"https:\/\/spmaskiner.com\/es\/cabezales-procesadores\/cabezales-procesadores-e\/cabezales-procesadores-sp-761-e\/sp-761-e-ficha-tecnica\/\" class=\"elementor-item menu-link\">Ficha t\u00e9cnica<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8082\"><a href=\"https:\/\/spmaskiner.com\/es\/cabezales-procesadores\/cabezales-procesadores-e\/cabezales-procesadores-sp-761-e\/sp-761-e-ventajas-para-el-cliente\/\" class=\"elementor-item menu-link\">Ventajas para el cliente<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8083\"><a href=\"https:\/\/spmaskiner.com\/es\/cabezales-procesadores\/cabezales-procesadores-e\/cabezales-procesadores-sp-761-e\/sp-761-e-sistemas-de-control\/\" class=\"elementor-item menu-link\">Sistemas de control<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8084\"><a href=\"https:\/\/spmaskiner.com\/es\/cabezales-procesadores\/cabezales-procesadores-e\/cabezales-procesadores-sp-761-e\/sp-761-e-accesorios-y-equipamiento\/\" class=\"elementor-item menu-link\">Accesorios y equipamiento<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Alternar men\u00fa\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-ed3ff97\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8080\"><a href=\"https:\/\/spmaskiner.com\/es\/cabezales-procesadores\/cabezales-procesadores-e\/cabezales-procesadores-sp-761-e\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Informaci\u00f3n del Producto<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8081\"><a href=\"https:\/\/spmaskiner.com\/es\/cabezales-procesadores\/cabezales-procesadores-e\/cabezales-procesadores-sp-761-e\/sp-761-e-ficha-tecnica\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Ficha t\u00e9cnica<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8082\"><a href=\"https:\/\/spmaskiner.com\/es\/cabezales-procesadores\/cabezales-procesadores-e\/cabezales-procesadores-sp-761-e\/sp-761-e-ventajas-para-el-cliente\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Ventajas para el cliente<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8083\"><a href=\"https:\/\/spmaskiner.com\/es\/cabezales-procesadores\/cabezales-procesadores-e\/cabezales-procesadores-sp-761-e\/sp-761-e-sistemas-de-control\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Sistemas de control<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8084\"><a href=\"https:\/\/spmaskiner.com\/es\/cabezales-procesadores\/cabezales-procesadores-e\/cabezales-procesadores-sp-761-e\/sp-761-e-accesorios-y-equipamiento\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Accesorios y equipamiento<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-687f00a5 control-system-section elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"687f00a5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6101bb3b\" data-id=\"6101bb3b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29049fe7 elementor-widget elementor-widget-heading\" data-id=\"29049fe7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Sistemas de control - SP 761 E<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5b909e4e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5b909e4e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4f625bf8\" data-id=\"4f625bf8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66d52413 elementor-widget elementor-widget-heading\" data-id=\"66d52413\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Compatible con la mayor\u00eda de los sistemas de control<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e962ca6 elementor-widget elementor-widget-text-editor\" data-id=\"2e962ca6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El SP 761 E se puede utilizar con pr\u00e1cticamente todos los sistemas de control del mercado. A trav\u00e9s de una simple adaptaci\u00f3n, el SP 661 LF puede ser utilizado junto con los siguientes sistemas:<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d0366d8 sp-table elementor-widget elementor-widget-text-editor\" data-id=\"7d0366d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>Dasa7<\/li>\n<li>Dasa5<\/li>\n<li>Dasa4<\/li>\n<li>Dasa4 Compact<\/li>\n<li>Dasa Forester<\/li>\n<li>John Deere Timbermatic<\/li>\n<li>Motomit IT<\/li>\n<li>Motomit PC<\/li>\n<li>Komatsu MAXI<\/li>\n<li>Ponsse Opti<\/li>\n<li>Technion<\/li>\n<li>Techno Matic<\/li>\n<li>TOC-MD<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4324b305\" data-id=\"4324b305\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7223ad3f elementor-widget elementor-widget-image\" data-id=\"7223ad3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/03\/styrsystem-.jpg\" class=\"attachment-large size-large wp-image-7473\" alt=\"\" srcset=\"https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/03\/styrsystem-.jpg 400w, https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/03\/styrsystem--300x200.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cd20058 elementor-widget elementor-widget-image\" data-id=\"4cd20058\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/04\/styrsystem-1024x512.png\" class=\"attachment-large size-large wp-image-7508\" alt=\"\" srcset=\"https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/04\/styrsystem-1024x512.png 1024w, https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/04\/styrsystem-300x150.png 300w, https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/04\/styrsystem-768x384.png 768w, https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/04\/styrsystem.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35779184 elementor-widget elementor-widget-heading\" data-id=\"35779184\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sistemas de control completos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2163faaf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2163faaf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-7f920bb1\" data-id=\"7f920bb1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b4f5edf elementor-widget elementor-widget-text-editor\" data-id=\"4b4f5edf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>SPd5Bucking<br \/>SPd5Bucking es un sistema de control y medici\u00f3n completo para el control del proceso de tala en un procesador forestal de acuerdo con StanForD. Este es nuestro sistema m\u00e1s avanzado y tiene soporte para estimar el derribo. El sistema tambi\u00e9n est\u00e1 totalmente integrado con el sistema de control y comunicaci\u00f3n dasa5. Toda la comunicaci\u00f3n con el operador se realiza a trav\u00e9s de dxPc, que es un PC m\u00f3vil con sistema operativo Windows 10, y almacena toda la informaci\u00f3n, por ejemplo, estad\u00edsticas o instrucciones. El ordenador dxPc dispone de una pantalla t\u00e1ctil, lo que facilita considerablemente el trabajo del operador.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-53d73360\" data-id=\"53d73360\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32e21c3a elementor-widget elementor-widget-text-editor\" data-id=\"32e21c3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>SPd5BuckingPrio<br \/>SPd5BuckingPrio es nuestro sistema intermedio. El sistema tiene soporte para el derribo prioritario y est\u00e1 equipado con un PC. SPd5BuckingPrio es un sistema de derribo un poco m\u00e1s simple combinado con la potencia de un PC para informes, comunicaci\u00f3n y otros programas. El derribo se basa en longitudes prioritarias con o sin clases de di\u00e1metro. SPd5BuckingPrio es ideal cuando no se requieren la estimaci\u00f3n de derribo y los informes de acuerdo con StanForD al mismo tiempo que se necesita un PC para la creaci\u00f3n de informes, la comunicaci\u00f3n y otros programas de PC. Toda la comunicaci\u00f3n con el operador se realiza a trav\u00e9s de dxPc.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-6f722c59\" data-id=\"6f722c59\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5272c283 elementor-widget elementor-widget-text-editor\" data-id=\"5272c283\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>SPd5BuckingPrio-C<br \/>SPd5BuckingPrio-C es un sistema de derribo que se centra en la simplicidad sin comprometer el control del cabezal, el rendimiento o la productividad. SPd5BuckingPrio-C tiene soporte para el derribo prioritario con o sin clases de di\u00e1metro y ha sido especialmente desarrollado para la tala donde no hay necesidad de reportes inal\u00e1mbricos de producci\u00f3n o el uso de programas de PC. SPd5Bucking Prio-C funciona con el sistema operativo Windows CE.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-6d759247\" data-id=\"6d759247\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-585d01ab elementor-widget elementor-widget-text-editor\" data-id=\"585d01ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Caja de cabina SPd5<br \/>Independientemente del sistema que elija previamente, puede obtenerlo con nuestra caja de cabina SPd5. La caja de cabina permite que los m\u00f3dulos de cabina SPd5 se instalen de forma r\u00e1pida, eficiente y con la m\u00e1xima calidad. La caja de cabina viene montada de f\u00e1brica en SP y se entrega completamente terminada y probada junto con el cabezal, lo que garantiza una conexi\u00f3n correcta y una puesta en marcha sin problemas. Gracias al montaje de los m\u00f3dulos electr\u00f3nicos en un entorno protegido dentro de la caja, se minimizan los problemas causados por da\u00f1os externos como la humedad, el polvo, la suciedad y los impactos.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>SP 761 E Sistemas de control &#8211; SP 761 E Compatible con la mayor\u00eda de los sistemas de control El SP 761 E se puede utilizar con pr\u00e1cticamente todos los sistemas de control del mercado. A trav\u00e9s de una simple adaptaci\u00f3n, el SP 661 LF puede ser utilizado junto con los siguientes sistemas: Dasa7 Dasa5 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":7753,"menu_order":308,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-7759","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SP 761 E Sistemas de control - SP Maskiner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spmaskiner.com\/es\/cabezales-procesadores\/cabezales-procesadores-e\/cabezales-procesadores-sp-761-e\/sp-761-e-sistemas-de-control\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SP 761 E Sistemas de control - SP Maskiner\" \/>\n<meta property=\"og:description\" content=\"SP 761 E Sistemas de control &#8211; SP 761 E Compatible con la mayor\u00eda de los sistemas de control El SP 761 E se puede utilizar con pr\u00e1cticamente todos los sistemas de control del mercado. A trav\u00e9s de una simple adaptaci\u00f3n, el SP 661 LF puede ser utilizado junto con los siguientes sistemas: Dasa7 Dasa5 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spmaskiner.com\/es\/cabezales-procesadores\/cabezales-procesadores-e\/cabezales-procesadores-sp-761-e\/sp-761-e-sistemas-de-control\/\" \/>\n<meta property=\"og:site_name\" content=\"SP Maskiner\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-17T09:18:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/03\/styrsystem-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"267\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spmaskiner.com\\\/es\\\/cabezales-procesadores\\\/cabezales-procesadores-e\\\/cabezales-procesadores-sp-761-e\\\/sp-761-e-sistemas-de-control\\\/\",\"url\":\"https:\\\/\\\/spmaskiner.com\\\/es\\\/cabezales-procesadores\\\/cabezales-procesadores-e\\\/cabezales-procesadores-sp-761-e\\\/sp-761-e-sistemas-de-control\\\/\",\"name\":\"SP 761 E Sistemas de control - SP Maskiner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spmaskiner.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spmaskiner.com\\\/es\\\/cabezales-procesadores\\\/cabezales-procesadores-e\\\/cabezales-procesadores-sp-761-e\\\/sp-761-e-sistemas-de-control\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spmaskiner.com\\\/es\\\/cabezales-procesadores\\\/cabezales-procesadores-e\\\/cabezales-procesadores-sp-761-e\\\/sp-761-e-sistemas-de-control\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spmaskiner.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/styrsystem-.jpg\",\"datePublished\":\"2021-06-14T14:57:08+00:00\",\"dateModified\":\"2025-10-17T09:18:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spmaskiner.com\\\/es\\\/cabezales-procesadores\\\/cabezales-procesadores-e\\\/cabezales-procesadores-sp-761-e\\\/sp-761-e-sistemas-de-control\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spmaskiner.com\\\/es\\\/cabezales-procesadores\\\/cabezales-procesadores-e\\\/cabezales-procesadores-sp-761-e\\\/sp-761-e-sistemas-de-control\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/spmaskiner.com\\\/es\\\/cabezales-procesadores\\\/cabezales-procesadores-e\\\/cabezales-procesadores-sp-761-e\\\/sp-761-e-sistemas-de-control\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spmaskiner.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/styrsystem-.jpg\",\"contentUrl\":\"https:\\\/\\\/spmaskiner.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/styrsystem-.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spmaskiner.com\\\/es\\\/cabezales-procesadores\\\/cabezales-procesadores-e\\\/cabezales-procesadores-sp-761-e\\\/sp-761-e-sistemas-de-control\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spmaskiner.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cabezales procesadores\",\"item\":\"https:\\\/\\\/spmaskiner.com\\\/es\\\/cabezales-procesadores\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cabezales procesadores E\",\"item\":\"https:\\\/\\\/spmaskiner.com\\\/es\\\/cabezales-procesadores\\\/cabezales-procesadores-e\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Cabezal procesador SP 761 E\",\"item\":\"https:\\\/\\\/spmaskiner.com\\\/es\\\/harvester-heads\\\/harvester-heads-e\\\/harvester-head-sp-761-e\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"SP 761 E Sistemas de control\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spmaskiner.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/spmaskiner.com\\\/es\\\/\",\"name\":\"SP Maskiner\",\"description\":\"Always ahead\",\"publisher\":{\"@id\":\"https:\\\/\\\/spmaskiner.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spmaskiner.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spmaskiner.com\\\/es\\\/#organization\",\"name\":\"SP Maskiner\",\"url\":\"https:\\\/\\\/spmaskiner.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/spmaskiner.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spmaskiner.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/spmaskiner-logotyp.png\",\"contentUrl\":\"https:\\\/\\\/spmaskiner.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/spmaskiner-logotyp.png\",\"width\":350,\"height\":65,\"caption\":\"SP Maskiner\"},\"image\":{\"@id\":\"https:\\\/\\\/spmaskiner.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SP 761 E Sistemas de control - SP Maskiner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spmaskiner.com\/es\/cabezales-procesadores\/cabezales-procesadores-e\/cabezales-procesadores-sp-761-e\/sp-761-e-sistemas-de-control\/","og_locale":"es_ES","og_type":"article","og_title":"SP 761 E Sistemas de control - SP Maskiner","og_description":"SP 761 E Sistemas de control &#8211; SP 761 E Compatible con la mayor\u00eda de los sistemas de control El SP 761 E se puede utilizar con pr\u00e1cticamente todos los sistemas de control del mercado. A trav\u00e9s de una simple adaptaci\u00f3n, el SP 661 LF puede ser utilizado junto con los siguientes sistemas: Dasa7 Dasa5 [&hellip;]","og_url":"https:\/\/spmaskiner.com\/es\/cabezales-procesadores\/cabezales-procesadores-e\/cabezales-procesadores-sp-761-e\/sp-761-e-sistemas-de-control\/","og_site_name":"SP Maskiner","article_modified_time":"2025-10-17T09:18:55+00:00","og_image":[{"width":400,"height":267,"url":"https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/03\/styrsystem-.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/spmaskiner.com\/es\/cabezales-procesadores\/cabezales-procesadores-e\/cabezales-procesadores-sp-761-e\/sp-761-e-sistemas-de-control\/","url":"https:\/\/spmaskiner.com\/es\/cabezales-procesadores\/cabezales-procesadores-e\/cabezales-procesadores-sp-761-e\/sp-761-e-sistemas-de-control\/","name":"SP 761 E Sistemas de control - SP Maskiner","isPartOf":{"@id":"https:\/\/spmaskiner.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spmaskiner.com\/es\/cabezales-procesadores\/cabezales-procesadores-e\/cabezales-procesadores-sp-761-e\/sp-761-e-sistemas-de-control\/#primaryimage"},"image":{"@id":"https:\/\/spmaskiner.com\/es\/cabezales-procesadores\/cabezales-procesadores-e\/cabezales-procesadores-sp-761-e\/sp-761-e-sistemas-de-control\/#primaryimage"},"thumbnailUrl":"https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/03\/styrsystem-.jpg","datePublished":"2021-06-14T14:57:08+00:00","dateModified":"2025-10-17T09:18:55+00:00","breadcrumb":{"@id":"https:\/\/spmaskiner.com\/es\/cabezales-procesadores\/cabezales-procesadores-e\/cabezales-procesadores-sp-761-e\/sp-761-e-sistemas-de-control\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spmaskiner.com\/es\/cabezales-procesadores\/cabezales-procesadores-e\/cabezales-procesadores-sp-761-e\/sp-761-e-sistemas-de-control\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/spmaskiner.com\/es\/cabezales-procesadores\/cabezales-procesadores-e\/cabezales-procesadores-sp-761-e\/sp-761-e-sistemas-de-control\/#primaryimage","url":"https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/03\/styrsystem-.jpg","contentUrl":"https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/03\/styrsystem-.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/spmaskiner.com\/es\/cabezales-procesadores\/cabezales-procesadores-e\/cabezales-procesadores-sp-761-e\/sp-761-e-sistemas-de-control\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spmaskiner.com\/es\/"},{"@type":"ListItem","position":2,"name":"Cabezales procesadores","item":"https:\/\/spmaskiner.com\/es\/cabezales-procesadores\/"},{"@type":"ListItem","position":3,"name":"Cabezales procesadores E","item":"https:\/\/spmaskiner.com\/es\/cabezales-procesadores\/cabezales-procesadores-e\/"},{"@type":"ListItem","position":4,"name":"Cabezal procesador SP 761 E","item":"https:\/\/spmaskiner.com\/es\/harvester-heads\/harvester-heads-e\/harvester-head-sp-761-e\/"},{"@type":"ListItem","position":5,"name":"SP 761 E Sistemas de control"}]},{"@type":"WebSite","@id":"https:\/\/spmaskiner.com\/es\/#website","url":"https:\/\/spmaskiner.com\/es\/","name":"SP Maskiner","description":"Always ahead","publisher":{"@id":"https:\/\/spmaskiner.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spmaskiner.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/spmaskiner.com\/es\/#organization","name":"SP Maskiner","url":"https:\/\/spmaskiner.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/spmaskiner.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/03\/spmaskiner-logotyp.png","contentUrl":"https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/03\/spmaskiner-logotyp.png","width":350,"height":65,"caption":"SP Maskiner"},"image":{"@id":"https:\/\/spmaskiner.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/spmaskiner.com\/es\/wp-json\/wp\/v2\/pages\/7759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spmaskiner.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/spmaskiner.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/spmaskiner.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/spmaskiner.com\/es\/wp-json\/wp\/v2\/comments?post=7759"}],"version-history":[{"count":2,"href":"https:\/\/spmaskiner.com\/es\/wp-json\/wp\/v2\/pages\/7759\/revisions"}],"predecessor-version":[{"id":11999,"href":"https:\/\/spmaskiner.com\/es\/wp-json\/wp\/v2\/pages\/7759\/revisions\/11999"}],"up":[{"embeddable":true,"href":"https:\/\/spmaskiner.com\/es\/wp-json\/wp\/v2\/pages\/7753"}],"wp:attachment":[{"href":"https:\/\/spmaskiner.com\/es\/wp-json\/wp\/v2\/media?parent=7759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}