{"id":5769,"date":"2021-04-09T11:03:01","date_gmt":"2021-04-09T09:03:01","guid":{"rendered":"https:\/\/spmaskiner.com\/tetes-dabattage\/tetes-dabattage-lf\/tetes-dabattage-sp-761-lf\/avantages-pour-les-clients\/"},"modified":"2021-09-21T16:02:28","modified_gmt":"2021-09-21T14:02:28","slug":"avantages-pour-les-clients","status":"publish","type":"page","link":"https:\/\/spmaskiner.com\/fr\/tetes-dabattage\/tetes-dabattage-lf\/tetes-dabattage-sp-761-lf\/avantages-pour-les-clients\/","title":{"rendered":"Avantages pour les clients"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5769\" class=\"elementor elementor-5769 elementor-3054\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d048f43 elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"2d048f43\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-677623be\" data-id=\"677623be\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a1c62bf elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"3a1c62bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SP 761 LF<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-23f5f463\" data-id=\"23f5f463\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1245f4f6 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1245f4f6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4698a2c2\" data-id=\"4698a2c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-93bdfee e--pointer-background elementor-nav-menu--dropdown-mobile ecs-nav-layout-horizontal e--animation-fade elementor-nav-menu--toggle elementor-nav-menu--burger ecs-toggle-align-center elementor-widget elementor-widget-global elementor-global-3067 elementor-widget-nav-menu\" data-id=\"93bdfee\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"product-menu\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;fas fa-caret-down&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-background e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-93bdfee\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5994\"><a href=\"https:\/\/spmaskiner.com\/fr\/tetes-dabattage\/tetes-dabattage-lf\/tetes-dabattage-sp-761-lf\/\" class=\"elementor-item menu-link\">Information produit<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5995\"><a href=\"https:\/\/spmaskiner.com\/fr\/tetes-dabattage\/tetes-dabattage-lf\/tetes-dabattage-sp-761-lf\/caracteristiques-techniques\/\" class=\"elementor-item menu-link\">Caract\u00e9ristiques techniques<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5996\"><a href=\"https:\/\/spmaskiner.com\/fr\/tetes-dabattage\/tetes-dabattage-lf\/tetes-dabattage-sp-761-lf\/avantages-pour-les-clients\/\" class=\"elementor-item menu-link\">Avantages pour les clients<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5997\"><a href=\"https:\/\/spmaskiner.com\/fr\/tetes-dabattage\/tetes-dabattage-lf\/tetes-dabattage-sp-761-lf\/systemes-de-commande\/\" class=\"elementor-item menu-link\">Syst\u00e8mes de commande<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5998\"><a href=\"https:\/\/spmaskiner.com\/fr\/tetes-dabattage\/tetes-dabattage-lf\/tetes-dabattage-sp-761-lf\/accessoires-et-equipement\/\" class=\"elementor-item menu-link\">Accessoires et \u00e9quipement<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Permuter le menu\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-93bdfee\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5994\"><a href=\"https:\/\/spmaskiner.com\/fr\/tetes-dabattage\/tetes-dabattage-lf\/tetes-dabattage-sp-761-lf\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Information produit<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5995\"><a href=\"https:\/\/spmaskiner.com\/fr\/tetes-dabattage\/tetes-dabattage-lf\/tetes-dabattage-sp-761-lf\/caracteristiques-techniques\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Caract\u00e9ristiques techniques<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5996\"><a href=\"https:\/\/spmaskiner.com\/fr\/tetes-dabattage\/tetes-dabattage-lf\/tetes-dabattage-sp-761-lf\/avantages-pour-les-clients\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Avantages pour les clients<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5997\"><a href=\"https:\/\/spmaskiner.com\/fr\/tetes-dabattage\/tetes-dabattage-lf\/tetes-dabattage-sp-761-lf\/systemes-de-commande\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Syst\u00e8mes de commande<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5998\"><a href=\"https:\/\/spmaskiner.com\/fr\/tetes-dabattage\/tetes-dabattage-lf\/tetes-dabattage-sp-761-lf\/accessoires-et-equipement\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Accessoires et \u00e9quipement<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-45f75c68 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"45f75c68\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b017ccc\" data-id=\"5b017ccc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb7f566 elementor-widget elementor-widget-heading\" data-id=\"fb7f566\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Avantages pour les clients - T\u00eates d\u2019abattage SP 761 LF<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40666573 elementor-widget elementor-widget-text-editor\" data-id=\"40666573\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-475de39 elementor-widget elementor-widget-text-editor\" data-id=\"475de39\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-text-editor elementor-clearfix\">\n<h2>D\u00e9tails<\/h2>\n<div>Toutes nos t\u00eates d\u2019abattage ont des fonctions utiles et ing\u00e9nieuses. Cliquez sur les croix cercl\u00e9es pour en savoir plus.<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6b55af49 detaljer elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6b55af49\" data-element_type=\"section\" data-e-type=\"section\" id=\"detaljer-sp761lf\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4cb23a1\" data-id=\"4cb23a1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60fb1079 elementor-widget elementor-widget-text-editor\" data-id=\"60fb1079\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"hotspot\"><img decoding=\"async\" class=\"img-responsive\" src=\"\/wp-content\/themes\/spmaskiner\/images\/hotspots\/sp761lf-hotspot-1.jpg\" \/><\/p>\n<div class=\"spots\">\n<div id=\"spot-01\">\n                                                    <a class=\"popoverBtn\" data-popupcontent=\"1\" data-placement=\"top\" data-content=\"Couteau sup\u00e9rieur fixe robuste, en acier haute r\u00e9sistance pour une longue dur\u00e9e de vie.\"><br \/>\n                                                    <i class=\"fa fa-2x fa-plus-circle animated infinite pulse\" aria-hidden=\"true\"><\/i><br \/>\n                                                    <\/a>\n                                                <\/div>\n<div id=\"spot-02\">\n                                                    <a class=\"popoverBtn\" data-popupcontent=\"1\" data-placement=\"top\" data-content=\"Les trois couteaux enveloppants sont en acier haute r\u00e9sistance et sont d\u2019une conception tr\u00e8s robuste pour une r\u00e9sistance et une dur\u00e9e de vie maximales.\"><br \/>\n                                                    <i class=\"fa fa-2x fa-plus-circle animated infinite pulse\" aria-hidden=\"true\"><\/i><br \/>\n                                                    <\/a>\n                                                <\/div>\n<div id=\"spot-03\">\n                                                    <a class=\"popoverBtn\" data-popupcontent=\"1\" data-placement=\"top\" data-content=\"La suspension des rouleaux d\u2019entra\u00eenement offre un angle proportionnel avec une force portante d\u2019autant plus importante que le tronc est gros.\"><br \/>\n                                                    <i class=\"fa fa-2x fa-plus-circle animated infinite pulse\" aria-hidden=\"true\"><\/i><br \/>\n                                                    <\/a>\n                                                <\/div>\n<div id=\"spot-04\">\n                                                    <a class=\"popoverBtn\" data-popupcontent=\"1\" data-placement=\"bottom\" data-content=\"La roulette de mesure est contr\u00f4l\u00e9e par un v\u00e9rin puissant et rapide. En combinaison avec une large amplitude de mouvement, cela garantit des r\u00e9sultats de mesure parfaits m\u00eame sur des tiges bossel\u00e9es et in\u00e9gales.\"><br \/>\n                                                    <i class=\"fa fa-2x fa-plus-circle animated infinite pulse\" aria-hidden=\"true\"><\/i><br \/>\n                                                    <\/a>\n                                                <\/div>\n<div id=\"spot-05\">\n                                                    <a class=\"popoverBtn\" data-popupcontent=\"1\" data-placement=\"top\" data-content=\"L\u2019unit\u00e9 de scie est la tr\u00e8s robuste et automatique Hultdins Supercut 100, avec lubrification int\u00e9gr\u00e9e et tension hydraulique de la cha\u00eene. Le moteur de 32 cc combin\u00e9 au syst\u00e8me QuickCut assure une coupe rapide et efficace.\"><br \/>\n                                                    <i class=\"fa fa-2x fa-plus-circle animated infinite pulse\" aria-hidden=\"true\"><\/i><br \/>\n                                                    <\/a>\n                                                <\/div>\n<div id=\"spot-06\">\n                                                    <a class=\"popoverBtn\" data-popupcontent=\"1\" data-placement=\"top\" data-content=\"Le couteau fixe int\u00e9gr\u00e9 dans le caisson de scie aide \u00e0 l\u2019\u00e9branchage de la partie inf\u00e9rieure de l\u2019arbre lors du positionnement pour l\u2019abattage.\"><br \/>\n                                                    <i class=\"fa fa-2x fa-plus-circle animated infinite pulse\" aria-hidden=\"true\"><\/i><br \/>\n                                                    <\/a>\n                                                <\/div>\n<div id=\"spot-07\">\n                                                    <a class=\"popoverBtn\" data-popupcontent=\"1\" data-placement=\"top\" data-content=\"Les moteurs de rouleau Poclain sont r\u00e9put\u00e9s pour leur fiabilit\u00e9 et leur couple \u00e9lev\u00e9 d\u00e8s le d\u00e9marrage. Diff\u00e9rentes cylindr\u00e9es sont disponibles pour optimisation selon les travaux et les porteurs.\"><br \/>\n                                                    <i class=\"fa fa-2x fa-plus-circle animated infinite pulse\" aria-hidden=\"true\"><\/i><br \/>\n                                                    <\/a>\n                                                <\/div>\n<div id=\"spot-08\">\n                                                    <a class=\"popoverBtn\" data-popupcontent=\"1\" data-placement=\"top\" data-content=\"Gr\u00e2ce \u00e0 la pi\u00e8ce centrale moul\u00e9e, le ch\u00e2ssis comprend un nombre tr\u00e8s r\u00e9duit d\u2019\u00e9l\u00e9ments. Le fait que le ch\u00e2ssis soit usin\u00e9 apr\u00e8s soudure garantit un ajustement parfait et un minimum de tension, ce qui se traduit par la plus grande robustesse possible en termes de durabilit\u00e9.\"><br \/>\n                                                    <i class=\"fa fa-2x fa-plus-circle animated infinite pulse\" aria-hidden=\"true\"><\/i><br \/>\n                                                    <\/a>\n                                                <\/div>\n<div id=\"spot-09\">\n                                                    <a class=\"popoverBtn\" data-popupcontent=\"1\" data-placement=\"top\" data-content=\"Gr\u00e2ce \u00e0 la pi\u00e8ce centrale moul\u00e9e, le ch\u00e2ssis comprend un nombre tr\u00e8s r\u00e9duit d\u2019\u00e9l\u00e9ments. Le fait que le ch\u00e2ssis soit usin\u00e9 apr\u00e8s soudure garantit un ajustement parfait et un minimum de tension, ce qui se traduit par la plus grande robustesse possible en termes de durabilit\u00e9.\"><br \/>\n                                                    <i class=\"fa fa-2x fa-plus-circle animated infinite pulse\" aria-hidden=\"true\"><\/i><br \/>\n                                                    <\/a>\n                                                <\/div>\n<\/p><\/div>\n<\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5d4bec2b\" data-id=\"5d4bec2b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-649e8e6a elementor-widget elementor-widget-text-editor\" data-id=\"649e8e6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"hotspot\"><img decoding=\"async\" src=\"\/wp-content\/themes\/spmaskiner\/images\/hotspots\/sp761lf-hotspot-2.jpg\" class=\"img-responsive\"><\/p>\n<div class=\"spots\">\n<div id=\"spot-10\">\n                                                    <a class=\"popoverBtn\" data-popupcontent=\"1\" data-placement=\"top\" data-content=\"Ch\u00e2ssis de tilt extr\u00eamement robuste et r\u00e9sistant \u00e0 la torsion. Les amortisseurs de tilt haut et bas minimisent les vibrations et l\u2019usure. Plaque de protection des flexibles et adaptateurs \u00e0 l\u2019int\u00e9rieur du ch\u00e2ssis de tilt.\"><br \/>\n                                                    <i class=\"fa fa-2x fa-plus-circle animated infinite pulse\" aria-hidden=\"true\"><\/i><br \/>\n                                                    <\/a>\n                                                <\/div>\n<div id=\"spot-11\">\n                                                    <a class=\"popoverBtn\" data-popupcontent=\"1\" data-placement=\"top\" data-content=\"V\u00e9rins de tilt plac\u00e9s \u00e0 l\u2019int\u00e9rieur du ch\u00e2ssis de tilt avec les raccords et flexibles derri\u00e8re les v\u00e9rins pour une protection optimale.\"><br \/>\n                                                    <i class=\"fa fa-2x fa-plus-circle animated infinite pulse\" aria-hidden=\"true\"><\/i><br \/>\n                                                    <\/a>\n                                                <\/div>\n<div id=\"spot-12\">\n                                                    <a class=\"popoverBtn\" data-popupcontent=\"1\" data-placement=\"bottom\" data-content=\"Capot robuste \u00e0 charni\u00e8res pour un entretien rapide et facile. L\u2019ajustement serr\u00e9 emp\u00eache l\u2019accumulation de salissures, d\u00e9bris et neige.\"><br \/>\n                                                    <i class=\"fa fa-2x fa-plus-circle animated infinite pulse\" aria-hidden=\"true\"><\/i><br \/>\n                                                    <\/a>\n                                                <\/div>\n<div id=\"spot-13\">\n                                                    <a class=\"popoverBtn\" data-popupcontent=\"1\" data-placement=\"top\" data-content=\"La mesure du diam\u00e8tre est li\u00e9e aux deux couteaux d\u2019\u00e9branchage sup\u00e9rieurs pour une meilleure pr\u00e9cision. Les encodeurs sont mont\u00e9s dans des bo\u00eetiers en acier compl\u00e8tement scell\u00e9s \u00e0 l\u2019int\u00e9rieur du ch\u00e2ssis pour une protection et une long\u00e9vit\u00e9 optimales.\"><br \/>\n                                                    <i class=\"fa fa-2x fa-plus-circle animated infinite pulse\" aria-hidden=\"true\"><\/i><br \/>\n                                                    <\/a>\n                                                <\/div>\n<div id=\"spot-14\">\n                                                    <a class=\"popoverBtn\" data-popupcontent=\"1\" data-placement=\"top\" data-content=\"Les couteaux d\u2019\u00e9branchage sont munis de longs tranchants effil\u00e9s de forme \u00e9tudi\u00e9e : les branches sont coup\u00e9es d\u00e9licatement au lieu d\u2019\u00eatre cass\u00e9es. Cela diminue les frottements pendant le d\u00e9filement et donne un r\u00e9sultat d\u2019\u00e9branchage parfait.\"><br \/>\n                                                    <i class=\"fa fa-2x fa-plus-circle animated infinite pulse\" aria-hidden=\"true\"><\/i><br \/>\n                                                    <\/a>\n                                                <\/div>\n<div id=\"spot-15\">\n                                                    <a class=\"popoverBtn\" data-popupcontent=\"1\" data-placement=\"top\" data-content=\"Les flexibles de moteur d\u2019entra\u00eenement sont plac\u00e9s sur le bras de moteur et totalement prot\u00e9g\u00e9s par un capot robuste pour minimiser les temps d\u2019arr\u00eat.\"><br \/>\n                                                    <i class=\"fa fa-2x fa-plus-circle animated infinite pulse\" aria-hidden=\"true\"><\/i><br \/>\n                                                    <\/a>\n                                                <\/div>\n<div id=\"spot-16\">\n                                                    <a class=\"popoverBtn\" data-popupcontent=\"1\" data-placement=\"top\" data-content=\"Le distributeur hydraulique est le tr\u00e8s fiable Parker L90\/K220 qui offre une excellente efficacit\u00e9 hydraulique et minimise les pertes d\u2019\u00e9nergie et l\u2019accumulation de chaleur. En combinaison avec le syst\u00e8me de commande informatique et le syst\u00e8me de pression proportionnelle, cela fait de la SP 761 LF une t\u00eate d\u2019abattage tr\u00e8s rapide, productive et \u00e9conome en carburant.\"><br \/>\n                                                    <i class=\"fa fa-2x fa-plus-circle animated infinite pulse\" aria-hidden=\"true\"><\/i><br \/>\n                                                    <\/a>\n                                                <\/div>\n<\/p><\/div>\n<\/p><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-80d5f30 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"80d5f30\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5bdb195\" data-id=\"5bdb195\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-357b672 elementor-position-right box-shadow elementor-vertical-align-top elementor-widget elementor-widget-global elementor-global-5852 elementor-global-727 elementor-widget-image-box\" data-id=\"357b672\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"333\" src=\"https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/03\/knivdesign.jpg\" class=\"attachment-full size-full wp-image-699\" alt=\"\" srcset=\"https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/03\/knivdesign.jpg 500w, https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/03\/knivdesign-300x200.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Les couteaux d\u2019\u00e9branchage <\/h3><p class=\"elementor-image-box-description\">sont \u00e9quip\u00e9s de bords de coupe longs sp\u00e9cialement con\u00e7us, qui permettent d\u2019\u00e9brancher en coupant plut\u00f4t qu\u2019en arrachant. Ceci minimise le frottement pendant l\u2019\u00e9branchage et augmente ainsi la vitesse et la productivit\u00e9. Les couteaux d\u2019\u00e9branchage sont moul\u00e9s en un acier haute r\u00e9sistance afin d\u2019offrir une durabilit\u00e9 et une dur\u00e9e de service maximales.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73b7248 elementor-position-right box-shadow elementor-vertical-align-top elementor-widget elementor-widget-global elementor-global-5854 elementor-global-730 elementor-widget-image-box\" data-id=\"73b7248\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"333\" src=\"https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/03\/lf_diagram_proportionella_tryck-thumb_sv-se.jpg\" class=\"attachment-full size-full wp-image-700\" alt=\"\" srcset=\"https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/03\/lf_diagram_proportionella_tryck-thumb_sv-se.jpg 500w, https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/03\/lf_diagram_proportionella_tryck-thumb_sv-se-300x200.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Les pressions proportionnelles<\/h3><p class=\"elementor-image-box-description\">permettent \u00e0 la t\u00eate de toujours utiliser automatiquement la pression optimale des couteaux d\u2019\u00e9branchage et des rouleaux d\u2019entra\u00eenement sur la tige, quel que soit le diam\u00e8tre de cette derni\u00e8re. Le frottement entre la tige et la t\u00eate est ainsi minimis\u00e9, ce qui garantit un entra\u00eenement le plus rapide et le plus souple possible. Des r\u00e9glages individuels pour les diff\u00e9rentes esp\u00e8ces d\u2019arbres permettent de maximiser encore plus la production.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b5d307e elementor-position-right box-shadow elementor-vertical-align-top elementor-widget elementor-widget-global elementor-global-5856 elementor-global-733 elementor-widget-image-box\" data-id=\"b5d307e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"333\" src=\"https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/03\/LogHold.jpg\" class=\"attachment-full size-full wp-image-707\" alt=\"\" srcset=\"https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/03\/LogHold.jpg 500w, https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/03\/LogHold-300x200.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">LogHold<\/h3><p class=\"elementor-image-box-description\">est un syst\u00e8me brevet\u00e9 et une \u00e9volution de la solution de pression proportionnelle permettant de minimiser davantage le frottement. LogHold permet de r\u00e9duire encore plus la pression des couteaux d\u2019\u00e9branchage contre la tige sans aucun risque de chute de la tige. Si la tige se met \u00e0 glisser, LogHold r\u00e9agit imm\u00e9diatement et augmente la pression de serrage \u00e0 un niveau suffisant pour maintenir la tige dans la position optimale. L\u2019augmentation du diam\u00e8tre avant la r\u00e9action de LogHold est d\u00e9finie individuellement pour chaque esp\u00e8ce d\u2019arbre dans le syst\u00e8me de commande.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3f1246 elementor-position-right box-shadow elementor-vertical-align-top elementor-widget elementor-widget-global elementor-global-5858 elementor-global-743 elementor-widget-image-box\" data-id=\"f3f1246\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"333\" src=\"https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/03\/vinkladematarhjul.jpg\" class=\"attachment-full size-full wp-image-736\" alt=\"\" srcset=\"https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/03\/vinkladematarhjul.jpg 500w, https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/03\/vinkladematarhjul-300x200.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">L\u2019angle proportionnel des rouleaux d\u2019entra\u00eenement<\/h3><p class=\"elementor-image-box-description\">modifie leur angle et leur capacit\u00e9 de charge en fonction du diam\u00e8tre de la tige. Lorsqu\u2019ils sont enti\u00e8rement ouverts pour le traitement d\u2019une tige d\u2019un diam\u00e8tre extr\u00eamement grand, les rouleaux d\u2019entra\u00eenement sont r\u00e9gl\u00e9s sur leur angle le plus large et offrent donc une capacit\u00e9 de charge maximale contre la tige. Ceci minimise la pression des couteaux d\u2019\u00e9branchage, ce qui r\u00e9duit le frottement et permet \u00e0 la t\u00eate d\u2019entra\u00eener plus rapidement et plus facilement la tige. Lorsque les rouleaux d\u2019entra\u00eenement sont ferm\u00e9s, cette solution unique permet d\u2019obtenir une t\u00eate tr\u00e8s \u00e9troite et agile aux dimensions compactes.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>SP 761 LF Avantages pour les clients &#8211; T\u00eates d\u2019abattage SP 761 LF D\u00e9tails Toutes nos t\u00eates d\u2019abattage ont des fonctions utiles et ing\u00e9nieuses. Cliquez sur les croix cercl\u00e9es pour en savoir plus. Kvistknivarna Kvistknivarna \u00e4r utrustade med l\u00e5nga och speciellt utformade kniveggar vilket g\u00f6r att kvistarna sk\u00e4rs av ist\u00e4llet f\u00f6r att brytas av. Detta [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":5758,"menu_order":33,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-5769","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avantages pour les clients - SP Maskiner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spmaskiner.com\/fr\/tetes-dabattage\/tetes-dabattage-lf\/tetes-dabattage-sp-761-lf\/avantages-pour-les-clients\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avantages pour les clients - SP Maskiner\" \/>\n<meta property=\"og:description\" content=\"SP 761 LF Avantages pour les clients &#8211; T\u00eates d\u2019abattage SP 761 LF D\u00e9tails Toutes nos t\u00eates d\u2019abattage ont des fonctions utiles et ing\u00e9nieuses. Cliquez sur les croix cercl\u00e9es pour en savoir plus. Kvistknivarna Kvistknivarna \u00e4r utrustade med l\u00e5nga och speciellt utformade kniveggar vilket g\u00f6r att kvistarna sk\u00e4rs av ist\u00e4llet f\u00f6r att brytas av. Detta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spmaskiner.com\/fr\/tetes-dabattage\/tetes-dabattage-lf\/tetes-dabattage-sp-761-lf\/avantages-pour-les-clients\/\" \/>\n<meta property=\"og:site_name\" content=\"SP Maskiner\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-21T14:02:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spmaskiner.com\/wp-content\/themes\/spmaskiner\/images\/hotspots\/sp761lf-hotspot-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spmaskiner.com\\\/fr\\\/tetes-dabattage\\\/tetes-dabattage-lf\\\/tetes-dabattage-sp-761-lf\\\/avantages-pour-les-clients\\\/\",\"url\":\"https:\\\/\\\/spmaskiner.com\\\/fr\\\/tetes-dabattage\\\/tetes-dabattage-lf\\\/tetes-dabattage-sp-761-lf\\\/avantages-pour-les-clients\\\/\",\"name\":\"Avantages pour les clients - SP Maskiner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spmaskiner.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spmaskiner.com\\\/fr\\\/tetes-dabattage\\\/tetes-dabattage-lf\\\/tetes-dabattage-sp-761-lf\\\/avantages-pour-les-clients\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spmaskiner.com\\\/fr\\\/tetes-dabattage\\\/tetes-dabattage-lf\\\/tetes-dabattage-sp-761-lf\\\/avantages-pour-les-clients\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spmaskiner.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/knivdesign.jpg\",\"datePublished\":\"2021-04-09T09:03:01+00:00\",\"dateModified\":\"2021-09-21T14:02:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spmaskiner.com\\\/fr\\\/tetes-dabattage\\\/tetes-dabattage-lf\\\/tetes-dabattage-sp-761-lf\\\/avantages-pour-les-clients\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spmaskiner.com\\\/fr\\\/tetes-dabattage\\\/tetes-dabattage-lf\\\/tetes-dabattage-sp-761-lf\\\/avantages-pour-les-clients\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/spmaskiner.com\\\/fr\\\/tetes-dabattage\\\/tetes-dabattage-lf\\\/tetes-dabattage-sp-761-lf\\\/avantages-pour-les-clients\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spmaskiner.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/knivdesign.jpg\",\"contentUrl\":\"https:\\\/\\\/spmaskiner.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/knivdesign.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spmaskiner.com\\\/fr\\\/tetes-dabattage\\\/tetes-dabattage-lf\\\/tetes-dabattage-sp-761-lf\\\/avantages-pour-les-clients\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spmaskiner.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00eates d\u2019abattage\",\"item\":\"https:\\\/\\\/spmaskiner.com\\\/fr\\\/tetes-dabattage\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"T\u00eates d\u2019abattage LF\",\"item\":\"https:\\\/\\\/spmaskiner.com\\\/fr\\\/skordaraggregat\\\/skordaraggregat-lf\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"T\u00eates d\u2019abattage SP 761 LF\",\"item\":\"https:\\\/\\\/spmaskiner.com\\\/fr\\\/skordaraggregat\\\/skordaraggregat-lf\\\/skordaraggregat-sp-761-lf\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Avantages pour les clients\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spmaskiner.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/spmaskiner.com\\\/fr\\\/\",\"name\":\"SP Maskiner\",\"description\":\"Always ahead\",\"publisher\":{\"@id\":\"https:\\\/\\\/spmaskiner.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spmaskiner.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spmaskiner.com\\\/fr\\\/#organization\",\"name\":\"SP Maskiner\",\"url\":\"https:\\\/\\\/spmaskiner.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/spmaskiner.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spmaskiner.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/spmaskiner-logotyp.png\",\"contentUrl\":\"https:\\\/\\\/spmaskiner.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/spmaskiner-logotyp.png\",\"width\":350,\"height\":65,\"caption\":\"SP Maskiner\"},\"image\":{\"@id\":\"https:\\\/\\\/spmaskiner.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avantages pour les clients - SP Maskiner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spmaskiner.com\/fr\/tetes-dabattage\/tetes-dabattage-lf\/tetes-dabattage-sp-761-lf\/avantages-pour-les-clients\/","og_locale":"fr_FR","og_type":"article","og_title":"Avantages pour les clients - SP Maskiner","og_description":"SP 761 LF Avantages pour les clients &#8211; T\u00eates d\u2019abattage SP 761 LF D\u00e9tails Toutes nos t\u00eates d\u2019abattage ont des fonctions utiles et ing\u00e9nieuses. Cliquez sur les croix cercl\u00e9es pour en savoir plus. Kvistknivarna Kvistknivarna \u00e4r utrustade med l\u00e5nga och speciellt utformade kniveggar vilket g\u00f6r att kvistarna sk\u00e4rs av ist\u00e4llet f\u00f6r att brytas av. Detta [&hellip;]","og_url":"https:\/\/spmaskiner.com\/fr\/tetes-dabattage\/tetes-dabattage-lf\/tetes-dabattage-sp-761-lf\/avantages-pour-les-clients\/","og_site_name":"SP Maskiner","article_modified_time":"2021-09-21T14:02:28+00:00","og_image":[{"url":"https:\/\/spmaskiner.com\/wp-content\/themes\/spmaskiner\/images\/hotspots\/sp761lf-hotspot-1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/spmaskiner.com\/fr\/tetes-dabattage\/tetes-dabattage-lf\/tetes-dabattage-sp-761-lf\/avantages-pour-les-clients\/","url":"https:\/\/spmaskiner.com\/fr\/tetes-dabattage\/tetes-dabattage-lf\/tetes-dabattage-sp-761-lf\/avantages-pour-les-clients\/","name":"Avantages pour les clients - SP Maskiner","isPartOf":{"@id":"https:\/\/spmaskiner.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spmaskiner.com\/fr\/tetes-dabattage\/tetes-dabattage-lf\/tetes-dabattage-sp-761-lf\/avantages-pour-les-clients\/#primaryimage"},"image":{"@id":"https:\/\/spmaskiner.com\/fr\/tetes-dabattage\/tetes-dabattage-lf\/tetes-dabattage-sp-761-lf\/avantages-pour-les-clients\/#primaryimage"},"thumbnailUrl":"https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/03\/knivdesign.jpg","datePublished":"2021-04-09T09:03:01+00:00","dateModified":"2021-09-21T14:02:28+00:00","breadcrumb":{"@id":"https:\/\/spmaskiner.com\/fr\/tetes-dabattage\/tetes-dabattage-lf\/tetes-dabattage-sp-761-lf\/avantages-pour-les-clients\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spmaskiner.com\/fr\/tetes-dabattage\/tetes-dabattage-lf\/tetes-dabattage-sp-761-lf\/avantages-pour-les-clients\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/spmaskiner.com\/fr\/tetes-dabattage\/tetes-dabattage-lf\/tetes-dabattage-sp-761-lf\/avantages-pour-les-clients\/#primaryimage","url":"https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/03\/knivdesign.jpg","contentUrl":"https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/03\/knivdesign.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/spmaskiner.com\/fr\/tetes-dabattage\/tetes-dabattage-lf\/tetes-dabattage-sp-761-lf\/avantages-pour-les-clients\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spmaskiner.com\/fr\/"},{"@type":"ListItem","position":2,"name":"T\u00eates d\u2019abattage","item":"https:\/\/spmaskiner.com\/fr\/tetes-dabattage\/"},{"@type":"ListItem","position":3,"name":"T\u00eates d\u2019abattage LF","item":"https:\/\/spmaskiner.com\/fr\/skordaraggregat\/skordaraggregat-lf\/"},{"@type":"ListItem","position":4,"name":"T\u00eates d\u2019abattage SP 761 LF","item":"https:\/\/spmaskiner.com\/fr\/skordaraggregat\/skordaraggregat-lf\/skordaraggregat-sp-761-lf\/"},{"@type":"ListItem","position":5,"name":"Avantages pour les clients"}]},{"@type":"WebSite","@id":"https:\/\/spmaskiner.com\/fr\/#website","url":"https:\/\/spmaskiner.com\/fr\/","name":"SP Maskiner","description":"Always ahead","publisher":{"@id":"https:\/\/spmaskiner.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spmaskiner.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/spmaskiner.com\/fr\/#organization","name":"SP Maskiner","url":"https:\/\/spmaskiner.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/spmaskiner.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/03\/spmaskiner-logotyp.png","contentUrl":"https:\/\/spmaskiner.com\/wp-content\/uploads\/2021\/03\/spmaskiner-logotyp.png","width":350,"height":65,"caption":"SP Maskiner"},"image":{"@id":"https:\/\/spmaskiner.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/spmaskiner.com\/fr\/wp-json\/wp\/v2\/pages\/5769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spmaskiner.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/spmaskiner.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/spmaskiner.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/spmaskiner.com\/fr\/wp-json\/wp\/v2\/comments?post=5769"}],"version-history":[{"count":0,"href":"https:\/\/spmaskiner.com\/fr\/wp-json\/wp\/v2\/pages\/5769\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/spmaskiner.com\/fr\/wp-json\/wp\/v2\/pages\/5758"}],"wp:attachment":[{"href":"https:\/\/spmaskiner.com\/fr\/wp-json\/wp\/v2\/media?parent=5769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}